{"id":5273,"date":"2026-08-14T10:12:56","date_gmt":"2026-08-14T08:12:56","guid":{"rendered":"https:\/\/t-w-b.org\/?p=5273"},"modified":"2026-08-14T10:24:33","modified_gmt":"2026-08-14T08:24:33","slug":"neuer-hilfstransport-mit-schulmoebel-fuer-osteuropa","status":"publish","type":"post","link":"https:\/\/t-w-b.org\/en\/2026\/08\/neuer-hilfstransport-mit-schulmoebel-fuer-osteuropa\/","title":{"rendered":"Neuer Hilfstransport mit Schulm\u00f6beln f\u00fcr Osteuropa"},"content":{"rendered":"<p>W\u00e4hrend der Sommerferien konnten wieder zwei Transporter mit gespendetem Schulmobiliar und technischer Ausstattung aus Wilhelmshaven und Umgebung nach Moldawien und Armenien gesendet werden. Dort wird die Ausstattung an unsere Netzwerkschulen vor Ort verteilt. Wir bedanken uns herzlich bei dem Schulamt Wilhelmshaven, dem <a href=\"https:\/\/cdh-stephanus.org\/\" target=\"_blank\">Christlichen Diakonischen Hilfswerk<\/a> &#8211; Bezirksverband Bremen e.V. f\u00fcr die Organisation und den Hilfstransport sowie bei allen flei\u00dfigen Helferinnen und Helfern!<\/p>\n<div class=\"boldPhotoSlide\"><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33366-1280x1707.jpg\" alt=\"33366\"><\/div><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33367-1280x1707.jpg\" alt=\"33367\"><\/div><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33370-1280x960.jpg\" alt=\"33370\"><\/div><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33371-1280x960.jpg\" alt=\"33371\"><\/div><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33372-1280x960.jpg\" alt=\"33372\"><\/div><div class=\"bpbItem\"><img decoding=\"async\" src=\"https:\/\/t-w-b.org\/wp-content\/uploads\/sites\/2\/2026\/08\/33374-1280x960.jpg\" alt=\"33374\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der Sommerferien konnten wieder zwei Transporter mit gespendetem Schulmobiliar und technischer Ausstattung aus Wilhelmshaven und Umgebung nach Moldawien und Armenien gesendet werden. Dort wird die Ausstattung an unsere Netzwerkschulen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":5285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,89,107,94],"tags":[],"class_list":["post-5273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lulog-de","category-moldawien","category-t-w-b-org","category-vereinsaktionen-de"],"_links":{"self":[{"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/posts\/5273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/comments?post=5273"}],"version-history":[{"count":4,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/posts\/5273\/revisions"}],"predecessor-version":[{"id":5288,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/posts\/5273\/revisions\/5288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/media\/5285"}],"wp:attachment":[{"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/media?parent=5273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/categories?post=5273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/t-w-b.org\/en\/wp-json\/wp\/v2\/tags?post=5273"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}